{"id":1108,"date":"2018-10-12T13:55:35","date_gmt":"2018-10-12T13:55:35","guid":{"rendered":"https:\/\/www.linnich-apotheke.de\/wp-cms\/?p=1108"},"modified":"2018-10-12T13:55:35","modified_gmt":"2018-10-12T13:55:35","slug":"goldrute","status":"publish","type":"post","link":"https:\/\/www.linnich-apotheke.de\/wp-cms\/goldrute\/","title":{"rendered":"Goldrute"},"content":{"rendered":"<p><a href=\"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-1110\" src=\"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/static.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute2-300x225.jpg 300w, https:\/\/static.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute2-768x576.jpg 768w, https:\/\/static.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute2.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Die Goldrute (Solidago virgaurea herba = Echtes Goldrutenkraut) ist in Europa, in den gem\u00e4\u00dfigten Klimazonen und in Nordafrika heimisch. Die Stauden wachsen gerne an sonnigen, trockenen, sandigen Standorten wie Ufergebieten, Waldlichtungen, Wiese und Bahnd\u00e4mmen. Sie k\u00f6nnen bis in den November hinein bl\u00fchen. Die goldgelben Korbbl\u00fcten erinnern an kleine strahlende Sonnen. Sie duften s\u00fc\u00dflich und aromatisch und werden gerne von zahlreichen Bienen, Schmetterlingen und weiteren Insekten besucht.<\/p>\n<p>In England und den USA werden Goldruten als Gartenpflanzen verwendet. Bei uns sind sie eher ungeliebt, da sie heimische Pflanzenarten zu verdr\u00e4ngen drohen.<\/p>\n<p>Die Goldrute ist au\u00dferdem die Nationalblume der US-Bundesstaaten Nebraska und Kentucky.<\/p>\n<p>Die Goldrute wird schon lange als Heilpflanze genutzt. Bei den Germanen z\u00e4hlte die Goldrute zu einem der besten Wundheilkr\u00e4uter. In alten Kr\u00e4uterb\u00fcchern aus dem 17. Jahrhundert hei\u00dft sie daher noch \u201eHeydnisch Wundkraut\u201c. Den Namen \u201eHeftkraut\u201c erhielt sie, weil sie Wunden zusammenheften kann.<\/p>\n<p>Sie wurde auch dazu verwendet, um \u00fcber den Gesundheitszustand eines Kranken Auskunft zu geben: Dazu stellte man die Goldrute \u00fcber Nacht neben das Bett eines Kranken. War sie am n\u00e4chsten Morgen verwelkt, wurde auch der Mensch nicht mehr gesund.<\/p>\n<p><a href=\"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1111\" src=\"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/static.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute3-300x200.jpg 300w, https:\/\/static.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute3-768x512.jpg 768w, https:\/\/static.linnich-apotheke.de\/wp-cms\/wp-content\/uploads\/2018\/10\/181012_bt_goldrute3.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Als Droge dienen die w\u00e4hrend der Bl\u00fcte gesammelten und schonend getrockneten oberirdischen Teile.<\/p>\n<p>F\u00fcr die Wirkung ist vermutlich nicht eine einzelne Substanz verantwortlich, sondern das Zusammenspiel von Flavonoiden, Triterpensaponinen und Phenolglykosiden. Flavonoide wirken aquaretisch. Das bedeutet, sie regen die Niere dazu an mehr Wasser auszuscheiden. Dadurch werden die ableitenden Harnwege (Harnleiter, Blas und Harnr\u00f6hre) besser durchsp\u00fclt und Keime ausgeschwemmt. Wichtig: Viel trinken!<\/p>\n<p>Zus\u00e4tzlich wirkt Goldrute antientz\u00fcndlich, leicht krampfl\u00f6send und beugt wohl Blasensteinen vor.<\/p>\n<p>Sie kann au\u00dferdem bei leichten Harnwegsinfekten helfen. K\u00fcndigt sich eine Blasenentz\u00fcndung durch klassische Beschwerden, wie zum Beispiel Brennen beim Wasserlassen an, eignet sich das Heilkraut als Tee oder in Tablettenform. In Tees kommen beide Goldrutenarten (Riesengoldrute) h\u00e4ufig kombiniert vor, ebenso wie andere Kr\u00e4uter, unter anderem Birkenbl\u00e4tter und Schachtelhalm.<\/p>\n<p>WICHTIG:<\/p>\n<ul>\n<li>Bessern sich die Symptome eines Harnwegsinfektes durch das pflanzliche Mittel nach kurzer Zeit nicht, wird ein Arztbesuch unumg\u00e4nglich!<\/li>\n<li>Wer unter Wasseransammlungen im K\u00f6rper (\u00d6demen) leidet, die durch eine Herzschw\u00e4che oder Nierenfunktionsst\u00f6rung bedingt sind, darf Goldrute nicht anwenden.<\/li>\n<li>Goldrute kann bei einer Blasenentz\u00fcndung nur helfen, wenn Sie ausreichend Fl\u00fcssigkeit trinken. Dann tritt der durchsp\u00fclende Effekt ein. Trinken ist bei einem Harnwegsinfekt ohnehin wichtig.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Lassen\u00a0 Sie sich zu Dosierung und Anwendung von uns beraten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Goldrute (Solidago virgaurea herba = Echtes Goldrutenkraut) ist in Europa, in den gem\u00e4\u00dfigten Klimazonen und in Nordafrika heimisch. Die Stauden wachsen gerne an sonnigen, trockenen, sandigen Standorten wie Ufergebieten, Waldlichtungen, Wiese und Bahnd\u00e4mmen. Sie k\u00f6nnen bis in den November hinein bl\u00fchen. Die goldgelben Korbbl\u00fcten erinnern an kleine strahlende Sonnen. Sie duften s\u00fc\u00dflich und aromatisch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/posts\/1108"}],"collection":[{"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/comments?post=1108"}],"version-history":[{"count":1,"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/posts\/1108\/revisions"}],"predecessor-version":[{"id":1112,"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/posts\/1108\/revisions\/1112"}],"wp:attachment":[{"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/media?parent=1108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/categories?post=1108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.linnich-apotheke.de\/wp-cms\/wp-json\/wp\/v2\/tags?post=1108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}